{"id":5451,"date":"2024-10-14T18:09:30","date_gmt":"2024-10-14T21:09:30","guid":{"rendered":"https:\/\/ojornalsergipe.com.br\/?p=5451"},"modified":"2024-10-14T18:09:31","modified_gmt":"2024-10-14T21:09:31","slug":"pm-prende-homem-em-flagrante-por-trafico-de-drogas-no-inacio-barbosa","status":"publish","type":"post","link":"https:\/\/ojornalsergipe.com.br\/index.php\/2024\/10\/14\/pm-prende-homem-em-flagrante-por-trafico-de-drogas-no-inacio-barbosa\/","title":{"rendered":"PM PRENDE HOMEM EM FLAGRANTE POR TR\u00c1FICO DE DROGAS NO IN\u00c1CIO BARBOSA"},"content":{"rendered":"\n<p>Um homem foi preso em flagrante por tr\u00e1fico il\u00edcito de drogas na madrugada do \u00faltimo dia 13, no bairro In\u00e1cio Barbosa, em Aracaju.<\/p>\n\n\n\n<p>Policiais da Radiopatrulha (BPRP), informaram que ao realizar rondas no bairro na regi\u00e3o do \u201cpantanal\u201d,&nbsp; foram parados por um popular que informou que estaria ocorrendo uma movimenta\u00e7\u00e3o suspeita na regi\u00e3o, aparentando ser tr\u00e1fico de drogas. O popular tamb\u00e9m informou aos policiais que um senhor de idade seria o respons\u00e1vel pela comercializa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ainda segundo informa\u00e7\u00f5es policiais, diante as informa\u00e7\u00f5es, a guarni\u00e7\u00e3o deslocou-se&nbsp;at\u00e9 o endere\u00e7o para verificar a proced\u00eancia das informa\u00e7\u00f5es. Ao chegar no local indicado foi poss\u00edvel sentir o forte odor de entorpecente vindo de uma resid\u00eancia, sendo poss\u00edvel visualizar um indiv\u00edduo cortando um \u201ctablete\u201d de subst\u00e2ncia an\u00e1loga \u00e0 maconha.<\/p>\n\n\n\n<p>Diante do flagrante, foi feita a abordagem no suspeito. Foi encontrado na resid\u00eancia tr\u00eas tabletes e uma por\u00e7\u00e3o de maconha e 23 pinos de coca\u00edna, al\u00e9m de uma uma balan\u00e7a de precis\u00e3o e rolo de papel alum\u00ednio, material utilizado para tr\u00e1fico de drogas.<\/p>\n\n\n\n<p>O suspeito e todo o material apreendido foram conduzidos a Central de Flagrantes para serem adotadas as medidas legais.<\/p>\n\n\n\n<p>Fonte: Infonet<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso em flagrante por tr\u00e1fico il\u00edcito de drogas na madrugada do \u00faltimo dia 13, no bairro In\u00e1cio Barbosa, em Aracaju. Policiais da Radiopatrulha (BPRP), informaram que ao realizar rondas no bairro na regi\u00e3o do \u201cpantanal\u201d,&nbsp; foram parados por um popular que informou que estaria ocorrendo uma movimenta\u00e7\u00e3o suspeita na regi\u00e3o, aparentando ser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[160],"tags":[152],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5451"}],"collection":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5451"}],"version-history":[{"count":1,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5451\/revisions"}],"predecessor-version":[{"id":5453,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5451\/revisions\/5453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5452"}],"wp:attachment":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}