{"id":5465,"date":"2024-10-21T19:43:41","date_gmt":"2024-10-21T22:43:41","guid":{"rendered":"https:\/\/ojornalsergipe.com.br\/?p=5465"},"modified":"2024-10-22T12:51:15","modified_gmt":"2024-10-22T15:51:15","slug":"suspeito-de-estupro-contra-cinco-familiares-e-preso-em-capela","status":"publish","type":"post","link":"https:\/\/ojornalsergipe.com.br\/index.php\/2024\/10\/21\/suspeito-de-estupro-contra-cinco-familiares-e-preso-em-capela\/","title":{"rendered":"SUSPEITO DE ESTUPRO CONTRA CINCO FAMILIARES \u00c9 PRESO EM CAPELA"},"content":{"rendered":"\n<p>A Pol\u00edcia Civil, por meio da Delegacia de Capela, prendeu um homem na manh\u00e3 desta segunda-feira, 21, ap\u00f3s concluir inqu\u00e9rito, o qual o indicia pelo estupro de cinco v\u00edtimas, entre elas, sua pr\u00f3pria filha.<\/p>\n\n\n\n<p>De acordo com o delegado Amaury Rocha, as investiga\u00e7\u00f5es iniciaram ap\u00f3s uma das v\u00edtimas, de 13 anos, comparecer \u00e0 delegacia para relatar os abusos sexuais praticados pelo padrasto.&nbsp;Segundo o relato, o crime acontecia&nbsp;h\u00e1 v\u00e1rios anos, e a jovem recebia constantes&nbsp;amea\u00e7as de morte contra a vida dela e de sua m\u00e3e, caso os fatos fossem relatados a algu\u00e9m.<\/p>\n\n\n\n<p>Durante a realiza\u00e7\u00e3o dos procedimentos investigativos, n\u00e3o somente foi&nbsp;confirmada&nbsp;a veracidade das informa\u00e7\u00f5es prestadas, assim como foram&nbsp;descobertas duas d\u00e9cadas de abusos sexuais cometidos pelo agressor contra suas enteadas. \u201cO homem \u00e9 casado h\u00e1 20 anos com a esposa, que j\u00e1 tinha quatro filhas e dois filhos, um deles deficiente, antes do relacionamento.&nbsp;Enquanto&nbsp;ela levava a crian\u00e7a para atendimento m\u00e9dico em Aracaju,&nbsp;ele abusava das quatro meninas. Na realidade, a v\u00edtima atual, a denunciante, \u00e9 sua pr\u00f3pria filha que foi concebida em um dos abusos contra uma das enteadas\u201d, esclarece o delegado.<\/p>\n\n\n\n<p>Exames de DNA constataram que o agressor tem quatro filhas, cada uma gerada pelas quatro enteadas abusadas anteriormente.<\/p>\n\n\n\n<p>Realizada a pris\u00e3o, o homem ser\u00e1 encaminhado ao Poder Judici\u00e1rio, para&nbsp;audi\u00eancia de cust\u00f3dia.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil refor\u00e7a que a den\u00fancia \u00e9 o primeiro passo para se quebrar o ciclo da viol\u00eancia. O sigilo da fonte \u00e9 garantido, ao utilizar o canal do&nbsp;Disque-Den\u00fancia (181).<\/p>\n\n\n\n<p><em>Fonte: SSP\/SE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil, por meio da Delegacia de Capela, prendeu um homem na manh\u00e3 desta segunda-feira, 21, ap\u00f3s concluir inqu\u00e9rito, o qual o indicia pelo estupro de cinco v\u00edtimas, entre elas, sua pr\u00f3pria filha. De acordo com o delegado Amaury Rocha, as investiga\u00e7\u00f5es iniciaram ap\u00f3s uma das v\u00edtimas, de 13 anos, comparecer \u00e0 delegacia para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[160],"tags":[152],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5465"}],"collection":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5465"}],"version-history":[{"count":1,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5465\/revisions"}],"predecessor-version":[{"id":5467,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5465\/revisions\/5467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5466"}],"wp:attachment":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}