{"id":5810,"date":"2025-02-07T09:35:45","date_gmt":"2025-02-07T12:35:45","guid":{"rendered":"https:\/\/ojornalsergipe.com.br\/?p=5810"},"modified":"2025-02-07T09:35:45","modified_gmt":"2025-02-07T12:35:45","slug":"hospital-nestor-piva-passa-a-funcionar-com-nova-gestao-e-tera-servico-de-fisioterapia","status":"publish","type":"post","link":"https:\/\/ojornalsergipe.com.br\/index.php\/2025\/02\/07\/hospital-nestor-piva-passa-a-funcionar-com-nova-gestao-e-tera-servico-de-fisioterapia\/","title":{"rendered":"Hospital Nestor Piva passa a funcionar com nova gest\u00e3o e ter\u00e1 servi\u00e7o de fisioterapia"},"content":{"rendered":"\n<p>A empresa cearense Instituto de Gest\u00e3o e Cidadania (IGC), assume a\u00a0gest\u00e3o do Hospital Nestor Piva, em\u00a0Aracaju, a partir desta sexta-feira (7). O valor anual do contrato, que \u00e9 emergencial, \u00e9 de cerca de R$ 46 milh\u00f5es.\u00a0<\/p>\n\n\n\n<p>Segundo a secret\u00e1ria Municipal de Sa\u00fade, D\u00e9bora Leite, um diferencial da nova gest\u00e3o \u00e9 o servi\u00e7o de fisioterapia oferecido aos pacientes.&nbsp;<\/p>\n\n\n\n<p>&#8220;O hospital tem estabiliza\u00e7\u00e3o, em que os pacientes ficam entubados em estado cr\u00edtico, muitas vezes aguardando uma UTI. No aguardo dessa UTI, queremos que ele tenha um cuidado pr\u00f3ximo ao da UTI. Pra isso, a fisioterapia \u00e9 extremamente importante&#8221;, disse.&nbsp;<\/p>\n\n\n\n<p>Outro ponto levantado foi que a equipe que j\u00e1 trabalhava no hospital deve continuar nesta nova gest\u00e3o.&nbsp;<\/p>\n\n\n\n<p>De acordo com o site da IGC, a empresa fundada em 2015 e com sede em Fortaleza (CE), atualmente administra cinco unidades de pronto atendimento, um hospital e um hospital-maternidade. Todos est\u00e3o localizados no interior do Cear\u00e1.\u00a0<br><\/p>\n\n\n\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa cearense Instituto de Gest\u00e3o e Cidadania (IGC), assume a\u00a0gest\u00e3o do Hospital Nestor Piva, em\u00a0Aracaju, a partir desta sexta-feira (7). O valor anual do contrato, que \u00e9 emergencial, \u00e9 de cerca de R$ 46 milh\u00f5es.\u00a0 Segundo a secret\u00e1ria Municipal de Sa\u00fade, D\u00e9bora Leite, um diferencial da nova gest\u00e3o \u00e9 o servi\u00e7o de fisioterapia oferecido [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[160],"tags":[152],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5810"}],"collection":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5810"}],"version-history":[{"count":1,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5810\/revisions"}],"predecessor-version":[{"id":5812,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5810\/revisions\/5812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5811"}],"wp:attachment":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}