{"id":8573,"date":"2026-05-13T10:43:43","date_gmt":"2026-05-13T13:43:43","guid":{"rendered":"https:\/\/ojornalsergipe.com.br\/?p=8573"},"modified":"2026-05-13T10:43:43","modified_gmt":"2026-05-13T13:43:43","slug":"bancos-devem-transferir-valores-nao-resgatados-a-fundo-publico","status":"publish","type":"post","link":"https:\/\/ojornalsergipe.com.br\/index.php\/2026\/05\/13\/bancos-devem-transferir-valores-nao-resgatados-a-fundo-publico\/","title":{"rendered":"BANCOS DEVEM TRANSFERIR VALORES N\u00c3O RESGATADOS A FUNDO P\u00daBLICO"},"content":{"rendered":"\n<p>At\u00e9 esta ter\u00e7a-feira (12), as institui\u00e7\u00f5es financeiras devem transferir eletronicamente os recursos n\u00e3o resgatados por correntistas para o Fundo Garantidor de Opera\u00e7\u00f5es (FGO).<\/p>\n\n\n\n<p>O prazo para transfer\u00eancia de recursos classificados como \u201cvalores a devolver\u201d foi definido por meio da Portaria Normativa&nbsp;n\u00ba 1.243\/2026, publicada na ter\u00e7a-feira (5).<\/p>\n\n\n\n<p>Do valor total acumulado na transfer\u00eancia, R$ 5 bilh\u00f5es ser\u00e3o destinados ao pagamento do risco de inadimpl\u00eancia nas opera\u00e7\u00f5es de cr\u00e9dito para cidad\u00e3os endividados.<\/p>\n\n\n\n<p>O servi\u00e7o \u00e9 fornecido pelo programa Extraordin\u00e1rio de Reequil\u00edbrio Financeiro das Fam\u00edlias \u2013 Novo Desenrola Brasil.<\/p>\n\n\n\n<p>A Desenrola 2.0 tem o objetivo de renegociar d\u00edvidas atrasadas da popula\u00e7\u00e3o que ganha at\u00e9 cinco sal\u00e1rios m\u00ednimos, o que corresponde a R$ 8.105 em 2026.<\/p>\n\n\n\n<p><strong>Valores<\/strong><\/p>\n\n\n\n<p>Segundo o Banco Central, os valores esquecidos por clientes em institui\u00e7\u00f5es financeiras do pa\u00eds alcan\u00e7aram R$ 10,57 bilh\u00f5es em mar\u00e7o. Desse total, R$ 8,13 bilh\u00f5es pertencem a 45,33 milh\u00f5es de pessoas f\u00edsicas, enquanto o valor restante corresponde a 5,04 milh\u00f5es de pessoas jur\u00eddicas, isto \u00e9, empresas.<\/p>\n\n\n\n<p>Entre as institui\u00e7\u00f5es, os bancos t\u00eam R$ 6,25 bilh\u00f5es dos valores dispon\u00edveis, seguidos por administradoras de cons\u00f3rcios (R$ 2,6 bilh\u00f5es) e cooperativas (R$ 975,3 milh\u00f5es)<\/p>\n\n\n\n<p>No balan\u00e7o mais recente, o Sistema de Valores a Receber (SVR) do Banco Central contabiliza que j\u00e1 foram devolvidos aos correntistas R$ 14,55 bilh\u00f5es esquecidos em contas.<\/p>\n\n\n\n<p><strong>Transfer\u00eancias<\/strong><\/p>\n\n\n\n<p>Uma vez conclu\u00eddas todas as transfer\u00eancias, o Minist\u00e9rio da Fazenda publicar\u00e1 um edital de chamamento no Di\u00e1rio Oficial da Uni\u00e3o, com informa\u00e7\u00f5es referentes ao valor exato transferido, o banco de origem, a ag\u00eancia e o n\u00famero da conta de onde o dinheiro veio.<\/p>\n\n\n\n<p>A portaria determina ainda que a consulta aos dados deve ser de acesso individualizado, em ambiente restrito, para seguran\u00e7a do correntista.<\/p>\n\n\n\n<p>Do total do saldo transferido ao FGO, 10% ser\u00e3o reservados para atender eventuais demandas de devolu\u00e7\u00e3o de valores aos respectivos benefici\u00e1rios.<\/p>\n\n\n\n<p>Fonte: A8se<\/p>\n","protected":false},"excerpt":{"rendered":"<p>At\u00e9 esta ter\u00e7a-feira (12), as institui\u00e7\u00f5es financeiras devem transferir eletronicamente os recursos n\u00e3o resgatados por correntistas para o Fundo Garantidor de Opera\u00e7\u00f5es (FGO). O prazo para transfer\u00eancia de recursos classificados como \u201cvalores a devolver\u201d foi definido por meio da Portaria Normativa&nbsp;n\u00ba 1.243\/2026, publicada na ter\u00e7a-feira (5). Do valor total acumulado na transfer\u00eancia, R$ 5 bilh\u00f5es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[160],"tags":[152],"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8573"}],"collection":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8573"}],"version-history":[{"count":1,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8573\/revisions"}],"predecessor-version":[{"id":8575,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8573\/revisions\/8575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/8574"}],"wp:attachment":[{"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ojornalsergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}